{"id":638,"date":"2026-03-16T06:59:00","date_gmt":"2026-03-16T07:59:00","guid":{"rendered":"http:\/\/peeksmarket.club\/?p=638"},"modified":"2026-03-18T10:09:13","modified_gmt":"2026-03-18T10:09:13","slug":"aurorizacion-previa-el-proceso-para-obtener-terapias-o-medicamentos-es-una-costosa-pesadilla-para-los-pacientes","status":"publish","type":"post","link":"https:\/\/peeksmarket.club\/index.php\/2026\/03\/16\/aurorizacion-previa-el-proceso-para-obtener-terapias-o-medicamentos-es-una-costosa-pesadilla-para-los-pacientes\/","title":{"rendered":"Aurorizacion previa, el proceso para obtener terapias o medicamentos, es una costosa pesadilla para los pacientes"},"content":{"rendered":"<p>Sheldon Ekirch est&#225; acostumbrada a sentirse decepcionada de su aseguradora de salud.<\/p>\n<p>Por eso, la joven de 31 a&#241;os, de Henrico, Virginia, se qued&#243; at&#243;nita cuando supo que Anthem finalmente tendr&#237;a que pagar un tratamiento m&#233;dico que le cambiar&#237;a la vida.<\/p>\n<p>Durante dos a&#241;os hab&#237;a luchado con la compa&#241;&#237;a para que cubriera infusiones de plasma sangu&#237;neo llamadas inmunoglobulina intravenosa, o IVIG. En algunos casos, el tratamiento ha demostrado mejorar los s&#237;ntomas asociados con la neuropat&#237;a de fibras peque&#241;as, una afecci&#243;n que hace que las extremidades de Ekirch se sientan como si estuvieran en llamas.<\/p>\n<p>Pero Anthem hab&#237;a negado repetidamente la cobertura de IVIG, que cuesta alrededor de $10.000 por infusi&#243;n. Luego, en febrero, una revisi&#243;n externa de su caso realizada para la Oficina de Seguros de Virginia (Virginia Bureau of Insurance) revoc&#243; la negativa de Anthem.<\/p>\n<p>Eso significaba que sus padres ya no tendr&#237;an que retirar dinero de los ahorros de jubilaci&#243;n de su padre para pagar el tratamiento de su propio bolsillo. Hasta entonces, ya hab&#237;an gastado unos $90.000.<\/p>\n<p>&#8220;Mi mam&#225; estaba sollozando. Mi pap&#225; estaba de rodillas, llorando. No creo haberlo visto llorar as&#237; nunca&#8221;, dijo Ekirch al describir la reacci&#243;n de sus padres ante la decisi&#243;n.<\/p>\n<p>&#8220;Creo que todav&#237;a estoy en shock por todo esto&#8221;, dijo.<\/p>\n<p>En una declaraci&#243;n preparada, Stephanie DuBois, vocera de Anthem Blue Cross and Blue Shield, dijo que el tratamiento IVIG no &#8220;se ajustaba a nuestros est&#225;ndares basados en evidencia&#8221;. Sin embargo, afirm&#243; que la compa&#241;&#237;a respeta &#8220;la decisi&#243;n del revisor externo&#8221; de revocar la negativa.<\/p>\n<p>Mientras tanto, cada a&#241;o millones de pacientes como Ekirch siguen enfrentando negativas a trav&#233;s del proceso de autorizaci&#243;n previa, que exige que muchos pacientes o sus doctores obtengan aprobaci&#243;n anticipada de las aseguradoras antes de continuar con la atenci&#243;n m&#233;dica.<\/p>\n<p>Y a pesar de las promesas de reforma de las aseguradoras, las negativas siguen siendo una caracter&#237;stica frustrante del sistema de salud.<\/p>\n<p>En junio pasado, funcionarios de la administraci&#243;n Trump anunciaron en una conferencia de prensa que l&#237;deres de las aseguradoras de salud se hab&#237;an comprometido a simplificar la autorizaci&#243;n previa tomando medidas como <a href=\"https:\/\/www.ahip.org\/news\/press-releases\/health-plans-take-action-to-simplify-prior-authorization\">&#8220;reducir el alcance de los reclamos&#8221;<\/a> que requieren aprobaci&#243;n anticipada. Tambi&#233;n prometieron tiempos de respuesta m&#225;s r&#225;pidos y &#8220;explicaciones claras y f&#225;ciles de entender&#8221; sobre sus decisiones.<\/p>\n<p>Sin embargo, en febrero, cuando KFF Health News contact&#243; a m&#225;s de una docena de grandes aseguradoras que firmaron el compromiso, la mitad de ellas no proporcion&#243; detalles espec&#237;ficos sobre los servicios de salud para los cuales ya no exigen autorizaci&#243;n previa.<\/p>\n<p>Un <a href=\"https:\/\/www.ahip.org\/news\/articles\/2026-will-bring-progress-on-simplifying-prior-authorization\">comunicado de prensa de enero<\/a> indic&#243; que la industria sigue comprometida con el esfuerzo. Pero doctores, consumidores y defensores de pacientes son pesimistas sobre la disposici&#243;n de las aseguradoras a cumplir con estos cambios voluntarios.<\/p>\n<p>&#8220;No tienen ning&#250;n deseo de hacer lo que es mejor para el paciente si eso va a afectar sus bolsillos&#8221;, dijo Matt Toresco, director ejecutivo de Archo Advocacy, una empresa de defensa y consultor&#237;a para pacientes.<\/p>\n<p>&#8220;En el mundo de los seguros, la responsabilidad fiduciaria no es con el paciente&#8221;, dijo. &#8220;Es con Wall Street&#8221;.<\/p>\n<p><strong>\u00bfUn cambio significativo?<\/strong><\/p>\n<p>El Departamento de Salud y Servicios Humanos de EE.UU. (HHS) no respondi&#243; a las preguntas para este art&#237;culo. Las pocas actualizaciones que el gobierno federal ha emitido desde junio sobre la reforma de la autorizaci&#243;n previa incluyen un <a href=\"https:\/\/www.hhs.gov\/press-room\/hhs-prescription-drug-price-transparency-rule.html\">anuncio de septiembre<\/a> sobre garantizar que los m&#233;dicos puedan enviar solicitudes de forma electr&#243;nica.<\/p>\n<p>AHIP, el grupo comercial de aseguradoras de salud que public&#243; el comunicado de enero, no proporcion&#243; informaci&#243;n sobre tratamientos, c&#243;digos, medicamentos o procedimientos espec&#237;ficos que sus miembros hayan eliminado del requisito de autorizaci&#243;n previa desde que firmaron el compromiso.<\/p>\n<p>&#8220;Tendremos actualizaciones adicionales sobre el progreso m&#225;s adelante esta primavera&#8221;, dijo Kelly Parsons, vocera de la Asociaci&#243;n Blue Cross Blue Shield, que representa a 33 compa&#241;&#237;as independientes de Blue Cross y Blue Shield. Tampoco ofreci&#243; detalles espec&#237;ficos.<\/p>\n<p>Las compa&#241;&#237;as de Blue Cross y Blue Shield que cubren pacientes en Alabama, Arkansas, Iowa, Michigan, Pennsylvania, Carolina del Sur, Dakota del Sur y Tennessee no respondieron a las preguntas para este art&#237;culo o remitieron las consultas a la Asociaci&#243;n Blue Cross Blue Shield.<\/p>\n<p>En contraste, otras aseguradoras s&#237; citaron ejemplos espec&#237;ficos de cambios.<\/p>\n<p>Aetna CVS Health comenz&#243; a agrupar autorizaciones previas para procedimientos musculoesquel&#233;ticos, as&#237; como para pacientes con c&#225;ncer de pulm&#243;n, mama y pr&#243;stata, dijo el vocero Phil Blando.<\/p>\n<p>Esta pr&#225;ctica permite que los proveedores presenten una sola solicitud de autorizaci&#243;n para el tratamiento de un paciente en lugar de varias.<\/p>\n<p>Y Humana elimin&#243; los requisitos de autorizaci&#243;n previa para servicios de diagn&#243;stico relacionados con colonoscop&#237;as, entre otros cambios, dijo el portavoz Mark Taylor.<\/p>\n<p>UnitedHealthcare, que fue objeto de intenso escrutinio por su uso de la autorizaci&#243;n previa tras <a href=\"https:\/\/www.pbs.org\/newshour\/politics\/most-americans-blame-insurance-profits-and-coverage-denials-alongside-killer-in-unitedhealthcare-ceo-death-poll-finds\">el asesinato<\/a> de uno de sus ejecutivos a finales de 2024, elimin&#243; el requisito de autorizaci&#243;n previa el 1 de enero para ciertos estudios de im&#225;genes nucleares, ultrasonidos obst&#233;tricos y procedimientos de ecocardiograma, entre otros cambios, dijo el vocero Matthew Rodriguez.<\/p>\n<p>Aun as&#237;, algunos expertos del sistema de salud dudan que estos cambios tengan mucho impacto.<\/p>\n<p>&#8220;Las aseguradoras han hecho promesas similares antes y no han cumplido con cambios significativos&#8221;, dijo Bobby Mukkamala, presidente de la Asociaci&#243;n M&#233;dica Estadounidense, que representa a doctores y estudiantes de medicina.<\/p>\n<p>En 2018, <a href=\"https:\/\/www.ahip.org\/resources\/2018-prior-authorization-consensus-statement\">varios grupos del sector salud<\/a>, incluidos AHIP y la Asociaci&#243;n Blue Cross Blue Shield, anunciaron una alianza &#8220;para identificar oportunidades de mejorar el proceso de autorizaci&#243;n previa&#8221;. Sin embargo, <a href=\"https:\/\/www.ama-assn.org\/press-center\/ama-press-releases\/ama-responds-health-insurers-try-again-prior-authorization-reform\">Mukkamala escribi&#243;<\/a> en respuesta al compromiso de junio que el proceso sigue siendo &#8220;costoso, ineficiente, poco transparente y, con demasiada frecuencia, peligroso para los pacientes&#8221;.<\/p>\n<p>&#8220;La transparencia es esencial para que todos puedan ver si realmente se est&#225;n produciendo reformas&#8221;, dijo a KFF Health News.<\/p>\n<p><strong>Entusiasmo moderado<\/strong><\/p>\n<p>La autorizaci&#243;n previa puede estar recibiendo m&#225;s atenci&#243;n pol&#237;tica, pero los datos muestran que los pacientes \u2014especialmente quienes tienen afecciones cr&#243;nicas que requieren tratamiento continuo\u2014 siguen enfrentando obst&#225;culos para recibir la atenci&#243;n recomendada por sus doctores.<\/p>\n<p>Entre los pacientes de ese grupo, el 39 % dijo que la autorizaci&#243;n previa es &#8220;la mayor carga&#8221; para recibir atenci&#243;n, seg&#250;n <a href=\"https:\/\/www.kff.org\/public-opinion\/kff-health-tracking-poll-prior-authorizations-rank-as-publics-biggest-burden-when-getting-health-care\/\">una encuesta reciente de KFF<\/a>, una organizaci&#243;n sin fines de lucro de informaci&#243;n sobre salud que incluye a KFF Health News.<\/p>\n<p>Eso es cierto para Payton Herres, 25 a&#241;os, de Dayton, Ohio, quien en 2012 tuvo un trasplante de coraz&#243;n, lo que requiere que tome un medicamento recetado contra el rechazo por el resto de su vida.<\/p>\n<p>Pero el a&#241;o pasado, dijo, Anthem neg&#243; la cobertura del costoso medicamento. Lo hab&#237;a estado tomando durante m&#225;s de 10 a&#241;os.<\/p>\n<p>&#8220;He estado con Anthem toda mi vida y, de repente \u2014no s&#233; qu&#233; pas&#243;\u2014 empezaron a neg&#225;rmelo una y otra vez&#8221;, dijo. &#8220;Casi me quedo sin medicamento&#8221;.<\/p>\n<p>DuBois, la vocera de Anthem, confirm&#243; que la compa&#241;&#237;a ha aprobado el medicamento. Cuando neg&#243; la cobertura, la empresa no hab&#237;a tomado en cuenta el historial de tratamiento de Herres, dijo DuBois.<\/p>\n<p>Pero Herres dijo que la compa&#241;&#237;a le exigir&#225; obtener una nueva autorizaci&#243;n para el medicamento en septiembre.<\/p>\n<p>&#8220;\u00bfVan a negar otras cosas tambi&#233;n?&#8221;, pregunt&#243;. &#8220;Espero no tener que seguir luchando as&#237; por el resto de mi vida&#8221;.<\/p>\n<p>Anna Hocum, de 25 a&#241;os, se prepara para una lucha similar. En 2024 y 2025, su aseguradora neg&#243; repetidamente la cobertura de un tratamiento costoso utilizado para ralentizar la progresi&#243;n de una afecci&#243;n gen&#233;tica rara que destruye la funci&#243;n de sus pulmones.<\/p>\n<p>&#8220;Simplemente pens&#233; que iba a morir&#8221;, dijo Hocum, de Milwaukee. &#8220;Estaba luchando por sobrevivir y luego estaba luchando para convencer a alguien de que merec&#237;a sobrevivir&#8221;.<\/p>\n<p>Al igual que con Ekirch, los padres de Hocum pagaron el tratamiento mientras esperaban que la compa&#241;&#237;a de seguros revocara las negativas iniciales. Amigos y familiares donaron m&#225;s de $30.000 a trav&#233;s de una campa&#241;a en GoFundMe para ayudar a cubrir los costos.<\/p>\n<p>Luego, la primavera pasada, Hocum dijo que su aseguradora revoc&#243; la negativa sin una explicaci&#243;n aparente. Pero la aprobaci&#243;n es v&#225;lida solo por 12 meses, por lo que necesitar&#225; otra autorizaci&#243;n previa este a&#241;o.<\/p>\n<p>&#8220;Da miedo&#8221;, dijo. &#8220;No est&#225; garantizado que lo acepten&#8221;.<\/p>\n<p>Aunque ahora es &#8220;un enorme alivio&#8221; que Anthem est&#233; obligada a cubrir el tratamiento de Ekirch, su madre no sabe si o c&#243;mo la familia recuperar&#225; el dinero que ya ha pagado.<\/p>\n<p>En una carta a Ekirch confirmando la decisi&#243;n del revisor externo, Anthem explic&#243; que la autorizaci&#243;n ser&#225; v&#225;lida por un a&#241;o a partir del 25 de septiembre de 2025. &#8220;Nos complace poder ofrecer una respuesta favorable en este caso&#8221;, escribi&#243; un analista de quejas y apelaciones de Anthem.<\/p>\n<p>Ekirch dijo que la carta resalt&#243; la hipocres&#237;a de la compa&#241;&#237;a.<\/p>\n<p>&#8220;Act&#250;an como si fueran una organizaci&#243;n benevolente que me est&#225; haciendo un favor&#8221;. En realidad, dijo, &#8220;pelearon conmigo con u&#241;as y dientes en cada paso del camino, hasta el punto de que hicieron de mi vida un infierno&#8221;.<\/p>\n<p>Ahora, el acceso de Ekirch a la IVIG podr&#237;a volver a estar en peligro. Su cobertura COBRA a trav&#233;s de Anthem vence a finales de marzo. En abril tendr&#225; que cambiar a un nuevo plan m&#233;dico, y se est&#225; preparando para otra ronda de autorizaciones previas.<\/p>\n<p>&#8220;Simplemente tengo mucho miedo de no tener la fuerza para pasar por todo lo que se necesita&#8221;, dijo Ekirch, &#8220;para luchar esta batalla otra vez&#8221;.<\/p>\n<p><a href=\"https:\/\/kffhealthnews.org\/about-us\">KFF Health News<\/a> is a national newsroom that produces in-depth journalism about health issues and is one of the core operating programs at KFF\u2014an independent source of health policy research, polling, and journalism. Learn more about <a href=\"https:\/\/www.kff.org\/about-us\/\">KFF<\/a>.<\/p>\n<h3>USE OUR CONTENT<\/h3>\n<p>This story can be republished for free (<a href=\"https:\/\/kffhealthnews.org\/news\/article\/psiquiatras-podrian-adoptar-biomarcadores-en-el-diagnostico-de-la-salud-mental\/view\/republish\/\">details<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sheldon Ekirch est&#225; acostumbrada a sentirse decepcionada de su aseguradora de salud. Por eso, la joven de 31 a&#241;os, de Henrico, Virginia, se qued&#243; at&#243;nita cuando supo que Anthem finalmente tendr&#237;a que pagar un tratamiento m&#233;dico que le cambiar&#237;a la vida. Durante dos a&#241;os hab&#237;a luchado con la compa&#241;&#237;a para que cubriera infusiones de plasma&hellip;<\/p>\n","protected":false},"author":1,"featured_media":640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/posts\/638"}],"collection":[{"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/comments?post=638"}],"version-history":[{"count":1,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/posts\/638\/revisions"}],"predecessor-version":[{"id":639,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/posts\/638\/revisions\/639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/media\/640"}],"wp:attachment":[{"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/media?parent=638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/categories?post=638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/tags?post=638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}