{"id":693,"date":"2026-03-05T09:00:00","date_gmt":"2026-03-05T10:00:00","guid":{"rendered":"http:\/\/peeksmarket.club\/?p=693"},"modified":"2026-03-18T10:09:35","modified_gmt":"2026-03-18T10:09:35","slug":"con-la-presencia-del-ice-habitantes-de-minnesota-crearon-un-sistema-medico-en-las-sombras-un-aprendizaje-para-otras-ciudades","status":"publish","type":"post","link":"https:\/\/peeksmarket.club\/index.php\/2026\/03\/05\/con-la-presencia-del-ice-habitantes-de-minnesota-crearon-un-sistema-medico-en-las-sombras-un-aprendizaje-para-otras-ciudades\/","title":{"rendered":"Con la presencia del ICE, habitantes de Minnesota crearon un sistema m\u00e9dico en las sombras. Un aprendizaje para otras ciudades"},"content":{"rendered":"<p>MINNEAPOLIS. \u2014 Gabi tiene grandes ojos color caf&#233;, trenzas y una afecci&#243;n gen&#233;tica que hace que sus huesos sean fr&#225;giles. Se fracturan con facilidad, lo que le provoca a la ni&#241;a de 2 a&#241;os tanto dolor que su madre dej&#243; su trabajo limpiando oficinas para quedarse en casa y cargarla por el apartamento de una habitaci&#243;n que comparten con seis familiares.<\/p>\n<p>Cuando agentes federales de inmigraci&#243;n llegaron a su ciudad, deportaron primero al padre de Gabi y luego a su t&#237;a.<\/p>\n<p>Gabi naci&#243; en Estados Unidos y es ciudadana estadounidense. Su mejor oportunidad de alg&#250;n d&#237;a pararse, o incluso caminar, es una cirug&#237;a compleja en las piernas y los pies que estaba programada para enero.<\/p>\n<p>Pero su madre, quien est&#225; tan asustada que ni siquiera se anima a sacar la basura, y mucho menos a atravesar la ciudad hasta el hospital, cancel&#243; el procedimiento. (En este art&#237;culo, KFF Health News y NPR acordaron identificar solo parcialmente a los pacientes y a sus familias porque temen convertirse en blanco de la ofensiva migratoria del presidente Donald Trump).<\/p>\n<p>&#8220;Quiero m&#225;s que nada, mi deseo, es que mi beb&#233; empiece a caminar&#8221;, dijo su madre, mientras Gabi se mov&#237;a en sus brazos, con una sonda de alimentaci&#243;n que sal&#237;a de su est&#243;mago conectada a un soporte de suero intravenoso. &#8220;Pero con la situaci&#243;n que est&#225; pasando, cancel&#233; la cita de cirug&#237;a porque le van a hacer cirug&#237;a en sus piernas y todas las citas de terapia f&#237;sica; lo cancel&#233; todo. Porque tengo miedo de salir&#8221;.<\/p>\n<p>El Departamento de Seguridad Nacional (DHS, por sus siglas en ingl&#233;s) declar&#243; el fin de lo que llam&#243; Operation Metro Surge (Operaci&#243;n Metro Surge), llevada a cabo por agentes del Servicio de Inmigraci&#243;n y Control de Aduanas (ICE, por sus siglas en ingl&#233;s) y de la Oficina de Aduanas y Protecci&#243;n Fronteriza (CBP, por sus siglas en ingl&#233;s). Aun as&#237;, trabajadores de salud dicen que los agentes de inmigraci&#243;n siguen apostados en los estacionamientos de hospitales. Y drones sobrevuelan zonas agr&#237;colas en las afueras de Minneapolis, donde inmigrantes somal&#237;es y latinos se han establecido en los &#250;ltimos a&#241;os.<\/p>\n<p>La ofensiva en Minnesota mostr&#243; el alcance del sistema de vigilancia y detenci&#243;n que la administraci&#243;n Trump est&#225; utilizando para desarraigar a comunidades inmigrantes del pa&#237;s y su fuerte impacto en el sistema de salud.<\/p>\n<p>Crisis de salud similares surgieron dondequiera que se concentraron oficiales de inmigraci&#243;n en el &#250;ltimo a&#241;o.<\/p>\n<p>En Dallas, cl&#237;nicas de salud p&#250;blica administraron unas 6.000 vacunas a latinos en agosto pasado, la mitad que en un programa similar un a&#241;o antes. En Chicago, a diario, doctores redirigieron a los pacientes de una cl&#237;nica a otra dependiendo de la actividad de ICE.<\/p>\n<p>\t\t\t\t\t<!-- image-left --><\/p>\n<p>\t\t\t\t\t<!-- image-right --><\/p>\n<p>En todo el pa&#237;s, las redadas redujeron las visitas de inmigrantes a servicios de salud.<\/p>\n<p>En Minnesota, los sistemas de salud reportaron tasas de cancelaci&#243;n y ausencias de hasta el 60 % desde diciembre. Un vocero del DHS culp&#243; a los manifestantes por la interrupci&#243;n. &#8220;Si alguien est&#225; impidiendo que los estadounidenses asistan a citas o recojan recetas, es un agitador violento que est&#225; bloqueando carreteras, embistiendo veh&#237;culos y da&#241;ando propiedad&#8221;, dijo.<\/p>\n<p>Mientras residentes de Minnesota protestaban en las calles contra el operativo, doctores y enfermeras organizaron en silencio redes m&#233;dicas informales para atender a pacientes en sus casas y evitar ser detectados.<\/p>\n<p>&#8220;Antes miraba a alguien a los ojos y dec&#237;a, de buena fe: \u2018Estar&#225;s bien en el hospital&#8217;&#8221;, dijo Emily Carroll, enfermera especializada en HealthFinders Collaborative, una cl&#237;nica comunitaria en Faribault, a unas 50 millas al sur de Minneapolis. &#8220;Pero ahora no puedo garantizar eso&#8221;.<\/p>\n<p>A medida que miles de agentes federales se retiran de Minneapolis, otras comunidades deben prepararse, dijo la senadora estatal dem&#243;crata de Minnesota, Alice Mann, quien es m&#233;dica.<\/p>\n<p>&#8220;S&#233; que suena extra&#241;o&#8221;, dijo, pero los proveedores de salud &#8220;necesitan empezar una red clandestina para llevar atenci&#243;n m&#233;dica a las casas. Porque dejar que la gente muera en su hogar o que est&#233; al borde de la muerte por miedo a ir al hospital, en 2026, es inaceptable&#8221;.<\/p>\n<p><strong>El operativo causa da&#241;os<\/strong><\/p>\n<p>Los m&#233;dicos dicen que las visitas a domicilio pueden ser la &#250;nica forma de llegar a quienes todav&#237;a se sienten bajo amenaza. En Los &#193;ngeles, desde junio, St. John&#8217;s Community Health llev&#243; atenci&#243;n m&#233;dica a unas 2.000 familias inmigrantes demasiado asustadas para salir durante un operativo migratorio, despu&#233;s de que las ausencias a citas superaran el 30%, dijo Jim Mangia, presidente de la organizaci&#243;n.<\/p>\n<p>Muchas de las grandes instituciones de salud de Minnesota han recurrido a la telemedicina y han usado menos la atenci&#243;n en el hogar.<\/p>\n<p>No as&#237; Munira Maalimisaq, cofundadora de Inspire Change Clinic en el vecindario Ventura Village de Minneapolis. Despu&#233;s de que cerca de un tercio de sus pacientes dejara de ir a sus citas, &#8220;pens&#233;: \u2018Tenemos que hacer algo&#8217;&#8221;, dijo la enfermera especializada. Entonces llam&#243; a una amiga doctora. \u00bfY si empezaran a ver pacientes en sus casas?<\/p>\n<p>&#8220;Y ella dijo: \u2018\u00bfSabes qu&#233;? Hag&#225;moslo&#8217;&#8221;.<\/p>\n<p>Ahora cuentan con unos 150 doctores, un equipo voluntario de &#8220;respuesta r&#225;pida&#8221; que ha realizado m&#225;s de 135 visitas domiciliarias. Su primera llamada fue para ver a una mujer cuyo esposo hab&#237;a sido deportado. Estaba en casa con sus hijos, con 39 semanas de embarazo y en trabajo de parto. Maalimisaq llam&#243; a una obstetra voluntaria y fueron a la casa.<\/p>\n<p>&#8220;Ten&#237;a 8 cent&#237;metros de dilataci&#243;n&#8221;, dijo Maalimisaq, &#8220;y no quer&#237;a que llam&#225;ramos a una ambulancia. Dec&#237;a: \u2018\u00bfPuedo tener al beb&#233; aqu&#237;?&#8217;&#8221;.<\/p>\n<p>La mujer no era una buena candidata para un parto en casa, dijo Maalimisaq. La convencieron de ir al hospital en el auto de Maalimisaq, un Tesla peque&#241;o con asientos blancos. &#8220;Todo lo que pod&#237;a salir mal, estaba ah&#237;&#8221;.<\/p>\n<p>Pero llegaron al hospital a tiempo y la mujer tuvo un parto seguro y saludable. &#8220;Si no hubi&#233;ramos estado all&#237;, no puedo imaginar lo que habr&#237;a pasado&#8221;.<\/p>\n<p>En otras visitas, dijo, ha visto &#8220;personas tan estresadas que se arrancaban el cabello&#8221;. Cont&#243; que conoci&#243; a una madre que estaba racionando el medicamento anticonvulsivo de su hijo, aunque el ni&#241;o hab&#237;a tenido &#8220;una convulsi&#243;n tras otra&#8221;.<\/p>\n<p>La administraci&#243;n Trump afirma que su operativo en Minnesota mejor&#243; la seguridad p&#250;blica. &#8220;Desde que comenz&#243; la Operaci&#243;n Metro Surge, nuestros valientes agentes del DHS han arrestado a m&#225;s de 4.000 extranjeros indocumentados con antecedentes penales, incluidos asesinos, violadores, ped&#243;filos y personas extremadamente peligrosas&#8221;, dijo Tricia McLaughlin, vocera del DHS.<\/p>\n<p>El DHS anunci&#243; la semana del 16 de febrero que McLaughlin dejar&#225; su cargo.<\/p>\n<p>Funcionarios correccionales de Minnesota dijeron que muchas personas acusadas de delitos fueron entregadas directamente a ICE por prisiones y c&#225;rceles estatales o del condado. Y <a href=\"https:\/\/www.factcheck.org\/2026\/01\/as-ice-arrests-increased-a-higher-portion-had-no-u-s-criminal-record\/\">solo el 29 % de los arrestos de ICE a nivel nacional<\/a> en enero fueron personas con condenas penales, seg&#250;n datos del DHS. Muchos menos hab&#237;an sido condenados por delitos violentos.<\/p>\n<p><strong>Agentes afuera de hospitales y cl&#237;nicas<\/strong><\/p>\n<p>En el primer d&#237;a de su segundo mandato, el presidente Donald Trump anul&#243; una pol&#237;tica de 2011 que prohib&#237;a la aplicaci&#243;n de leyes migratorias en &#8220;lugares sensibles&#8221; como iglesias, escuelas y hospitales.<\/p>\n<p>En Northfield, a unas 45 millas al sur de Minneapolis, agentes del ICE han estado sentados en sus autos durante horas, al menos dos veces por semana, fuera de cl&#237;nicas de salud, incluida una que opera el hospital del pueblo, dijo Carroll. Los agentes han realizado arrestos en la zona casi todos los d&#237;as, seg&#250;n Carroll y sus colegas.<\/p>\n<p>&#8220;El ICE no realiza operativos en hospitales, punto&#8221;, dijo McLaughlin.<\/p>\n<p>Una ma&#241;ana reciente, tres veh&#237;culos del ICE estaban en el estacionamiento de una iglesia bautista frente a una escuela primaria en Northfield, mientras voluntarios transportaban a 35 hijos de inmigrantes hacia y desde la escuela para que sus padres no tuvieran que salir, dijo Carroll.<\/p>\n<p>&#8220;El ICE no va a las escuelas para arrestar a ni&#241;os; estamos protegiendo a los ni&#241;os&#8221;, dijo McLaughlin.<\/p>\n<p>Drones sobrevuelan la mayor&#237;a de las noches y a veces durante el d&#237;a, sobre un parque de casas m&#243;viles donde viven principalmente inmigrantes que se mudaron a la zona para trabajar en agricultura y manufactura en los &#250;ltimos 15 a&#241;os. Las familias cubren las ventanas con papel, dijo Carroll.<\/p>\n<p>&#8220;No puedes sentirte seguro en ning&#250;n lugar&#8221;, dijo. &#8220;Camino a la escuela, camino a la cl&#237;nica, puedes encontrarte con el ICE. El miedo y la sensaci&#243;n de estar atrapados que viven estas familias son inaceptables&#8221;.<\/p>\n<p>Ese miedo significa que pacientes con diabetes y enfermedades card&#237;acas est&#225;n perdiendo controles de az&#250;car en sangre y de anticoagulaci&#243;n. No est&#225;n haciendo ejercicio y las personas con enfermedades cr&#243;nicas est&#225;n empeorando, dijo Calla Brown, pediatra en Minneapolis.<\/p>\n<p>En la cl&#237;nica de Faribault, donde trabaja Carroll, el personal entrega medicamentos, comida y otras necesidades a los pacientes. Un empleado transporta cada d&#237;a a 12 estudiantes de escuela media y secundaria en una camioneta de la cl&#237;nica.<\/p>\n<p>Algunos pacientes reciben atenci&#243;n en casa. Carroll diagnostic&#243; recientemente a un beb&#233; con influenza y les dijo a los padres que no era una amenaza inmediata, por ahora.<\/p>\n<p>&#8220;\u2018Si ven que el beb&#233; tiene dificultad para respirar, si no est&#225; comiendo, si no moja pa&#241;ales, tienen que ir al hospital&#8217;&#8221;, cont&#243; Carroll que les dijo. &#8220;\u2018No puedo prometer que sea seguro. Pero tienen que ir&#8217;&#8221;.<\/p>\n<p><strong>&#8220;Somos amables entre nosotros&#8221;<\/strong><\/p>\n<p>En Minneapolis, la enfermera partera Fernanda Honebrink pasa la mayor parte del d&#237;a llamando, coordinando y traslad&#225;ndose entre un grupo creciente de personas con miedo que permanecen en sus casas. Prefiere no llamarlo una red m&#233;dica clandestina.<\/p>\n<p>&#8220;Es m&#225;s bien as&#237; como funcionamos en Minnesota&#8221;, dijo Honebrink, ciudadana estadounidense que emigr&#243; de Ecuador hace 23 a&#241;os. &#8220;Somos amables entre nosotros&#8221;.<\/p>\n<p>Honebrink pas&#243; una tarde reciente en la casa de una familia con un beb&#233;. Sus padres, Alex e Isa, quieren que reciba vacunas y an&#225;lisis de sangre en su cita de control cuando cumpla 1 a&#241;o.<\/p>\n<p>Pero no han salido de su apartamento en m&#225;s de un mes. &#8220;No sabes qu&#233; es m&#225;s importante: salir por su bienestar o salir pensando que quiz&#225;s no regreses&#8221;, dijo Alex.<\/p>\n<p>La pareja venezolana entr&#243; legalmente a Estados Unidos en 2024 bajo un programa llamado Humanitarian Parole, que Trump finaliz&#243; en mayo. Desde entonces, agentes federales han detenido y deportado trabajadores de una empresa donde Alex, ingeniero mec&#225;nico, trabajaba en construcci&#243;n.<\/p>\n<p>Han visto veh&#237;culos del gobierno afuera de su casa. Dijeron conocer a un hombre que ten&#237;a documentos de trabajo v&#225;lidos, pero fue detenido cuando caminaba a la iglesia un domingo, trasladado a Texas y luego enviado en avi&#243;n a Venezuela. Era una perspectiva aterradora para quienes huyeron de la dictadura y la crisis econ&#243;mica de ese pa&#237;s.<\/p>\n<p>&#8220;Se siente como un ataque psicol&#243;gico&#8221;, dijo Alex. &#8220;La posibilidad de ser separado de tu familia&#8221;.<\/p>\n<p>Isa, abogada en Venezuela, ha sufrido depresi&#243;n posparto, encerrada durante semanas en su apartamento. El programa estatal que proporcionaba seguro m&#233;dico a todos los inmigrantes termin&#243; el 1 de enero. Una terapeuta la llama ocasionalmente sin costo.<\/p>\n<p>Ha intentado sostener a la familia vendiendo pasteles y collares hechos en casa y cuidando ni&#241;os.<\/p>\n<p>Su mayor temor es que la separen de su hijo, que naci&#243; en Estados Unidos y es ciudadano. No hab&#237;a considerado esa posibilidad hasta que un conocido le sugiri&#243; firmar <a href=\"https:\/\/www.ice.gov\/doclib\/foia\/policy\/delegateParentalAuthorityPacket_Jun2021.pdf\">un formulario<\/a> para designar a alguien para la custodia temporal en caso de que fuera deportada.<\/p>\n<p>&#8220;Fue algo que nunca imagin&#233;&#8221;, dijo Isa, llorando al recordarlo. &#8220;\u00a1Es mi beb&#233;! \u00a1No es de otra persona! \u00bfQu&#233;? \u00bfMi beb&#233; se quedar&#237;a aqu&#237; con alguien m&#225;s?&#8217;&#8217;<\/p>\n<p>Honebrink intervino de inmediato: &#8220;Yo me har&#233; responsable de &#233;l. Firmar&#233; el formulario&#8221;.<\/p>\n<p>M&#225;s tarde dijo a una reportera: &#8220;Le dije a mi esposo que no har&#237;a eso. Ya he firmado como patrocinadora de cuatro ni&#241;os&#8221;.<\/p>\n<p>En cuanto sali&#243; del apartamento, Honebrink volvi&#243; al tel&#233;fono y coordin&#243; con pediatras, programadores de cl&#237;nicas y voluntarios locales. En pocas horas, hab&#237;a conseguido una nueva cita de control para el beb&#233; y hab&#237;a encontrado un conductor verificado para transportar a la familia.<\/p>\n<p>&#8220;Una persona blanca&#8221;, explic&#243; Honebrink.<\/p>\n<p>Dos d&#237;as despu&#233;s, envi&#243; una foto de su peque&#241;a victoria: el beb&#233; de Alex e Isa con una curita en las piernas. &#8220;Recibi&#243; sus vacunas&#8221;, escribi&#243; por mensaje de texto. &#8220;Estoy muy feliz&#8221;.<\/p>\n<p>Pero otras necesidades m&#233;dicas no pueden resolverse con la misma rapidez. Una noche de febrero, Honebrink visit&#243; a Gabi y a su madre con el ba&#250;l del auto lleno de toallitas h&#250;medas, pa&#241;ales y juguetes donados.<\/p>\n<p>La cirug&#237;a de Gabi fue reprogramada para agosto. Su madre dijo que espera que para entonces sea seguro salir de casa.<\/p>\n<p>&#8220;Antes llevaba a los ni&#241;os al parque, pero ahora no salimos para nada&#8221;, dijo. &#8220;Agarran a la gente y la maltratan. Da miedo salir. \u00a1Ojal&#225; que se termine pronto lo que est&#225; pasando!&#8221;.<\/p>\n<p><em>Jackie Forti&#233;r, de KFF Health News, colabor&#243; con este art&#237;culo.<\/em><\/p>\n<p><em>[Aclaraci&#243;n: Este art&#237;culo fue revisado a las 11 am ET del 6 de marzo de 2026, para aclarar que agentes del Servicio de Inmigraci&#243;n y Control de Aduanas de Estados Unidos se hab&#237;an posicionado cerca de cl&#237;nicas, incluida una propiedad de un hospital].<\/em><\/p>\n<p><a href=\"https:\/\/kffhealthnews.org\/about-us\">KFF Health News<\/a> is a national newsroom that produces in-depth journalism about health issues and is one of the core operating programs at KFF\u2014an independent source of health policy research, polling, and journalism. Learn more about <a href=\"https:\/\/www.kff.org\/about-us\/\">KFF<\/a>.<\/p>\n<h3>USE OUR CONTENT<\/h3>\n<p>This story can be republished for free (<a href=\"https:\/\/kffhealthnews.org\/news\/article\/con-la-presencia-del-ice-habitantes-de-minnesota-crearon-un-sistema-medico-en-las-sombras-un-aprendizaje-para-otras-ciudades\/view\/republish\/\">details<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MINNEAPOLIS. \u2014 Gabi tiene grandes ojos color caf&#233;, trenzas y una afecci&#243;n gen&#233;tica que hace que sus huesos sean fr&#225;giles. Se fracturan con facilidad, lo que le provoca a la ni&#241;a de 2 a&#241;os tanto dolor que su madre dej&#243; su trabajo limpiando oficinas para quedarse en casa y cargarla por el apartamento de una&hellip;<\/p>\n","protected":false},"author":1,"featured_media":695,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/posts\/693"}],"collection":[{"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/comments?post=693"}],"version-history":[{"count":1,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/posts\/693\/revisions"}],"predecessor-version":[{"id":694,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/posts\/693\/revisions\/694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/media\/695"}],"wp:attachment":[{"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/media?parent=693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/categories?post=693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/peeksmarket.club\/index.php\/wp-json\/wp\/v2\/tags?post=693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}